{"id":101,"count":2,"description":"","link":"https:\/\/coccolatevi.it\/es\/category\/detersivo-lavatrice\/","name":"Detergente para lavadoras","slug":"detersivo-lavatrice","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/coccolatevi.it\/es\/wp-json\/wp\/v2\/categories\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coccolatevi.it\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/coccolatevi.it\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/coccolatevi.it\/es\/wp-json\/wp\/v2\/posts?categories=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}