{"id":4536,"date":"2025-11-27T08:04:03","date_gmt":"2025-11-27T08:04:03","guid":{"rendered":"https:\/\/coccolatevi.it\/?page_id=4536"},"modified":"2026-03-05T16:42:20","modified_gmt":"2026-03-05T15:42:20","slug":"informativa-ecommerce","status":"publish","type":"page","link":"https:\/\/coccolatevi.it\/de\/informativa-ecommerce\/","title":{"rendered":"Informationen zum elektronischen Gesch\u00e4ftsverkehr"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4536\" class=\"elementor elementor-4536\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b4b550 e-flex e-con-boxed e-con e-parent\" data-id=\"7b4b550\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ca2780 elementor-widget elementor-widget-heading\" data-id=\"0ca2780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informativa ecommerce<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec5bd13 elementor-widget elementor-widget-text-editor\" data-id=\"ec5bd13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"s4\"><strong><span class=\"s3\">INFORMATIVA PRIVACY AI SENSI DELL\u2019ART. 13 DEL REGOLAMENTO UE 2016\/679<\/span><\/strong><\/p><p class=\"s5\"><span class=\"s3\">p<\/span><span class=\"s3\">er i Clienti dell\u2019e-commerce, in relazione all\u2019acquisto e alla consegna dei prodotti <\/span><span class=\"s3\">Euthalia<\/span><span class=\"s3\"> nonch\u00e9 ai servizi di customer care<\/span><span class=\"s3\">,<\/span> <span class=\"s3\">allo svolgimento dell\u2019attivit\u00e0 di marketing, di profilazione e alle ricerche di mercato<\/span><\/p><p class=\"s7\"><a name=\"_Hlk17300963\"><\/a><span class=\"s6\">Per noi la protezione dei dati \u00e8 un argomento molto serio per cui desideriamo informarLa in merito all<\/span><span class=\"s6\">e<\/span><span class=\"s6\"> modalit\u00e0 con l<\/span><span class=\"s6\">e<\/span><span class=\"s6\"> qual<\/span><span class=\"s6\">i<\/span><span class=\"s6\">i dati vengono trattati e<\/span><span class=\"s6\">d<\/span><span class=\"s6\"> ai diritti che Lei pu\u00f2 esercitare ai sensi dell<\/span><span class=\"s6\">a<\/span> <span class=\"s6\">vigente<\/span><span class=\"s6\"> normativ<\/span><span class=\"s6\">a<\/span><span class=\"s6\"> sulla protezione dei dati, <\/span><span class=\"s6\">in particolare del <\/span><span class=\"s6\">Regolamento UE 2016\/679 (di seguito <\/span><span class=\"s6\">anche: \u201cGDPR\u201d).<\/span><\/p><p class=\"s7\"><span class=\"s6\">Questa informativa riguarda le attivit\u00e0 <\/span><span class=\"s6\">connesse all\u2019acquisto<\/span> <span class=\"s6\">dei<\/span><span class=\"s6\"> prodotti<\/span> <span class=\"s6\">commercializzati tramite il canale e-commerce \u201cCoccolatevi\u201d<\/span><span class=\"s6\">, <\/span><span class=\"s6\">raggiungibile dal sito web <\/span><a href=\"https:\/\/coccolatevi.it\/\"><span class=\"s8\">https:\/\/coccolatevi.it\/<\/span><\/a><span class=\"s6\"> (di seguito denominato: \u201cil Sito\u201d)<\/span><span class=\"s6\">,<\/span><span class=\"s6\"> nonch\u00e9<\/span> <span class=\"s6\">a<\/span><span class=\"s6\">i servizi di customer care e<\/span> <span class=\"s6\">al<\/span><span class=\"s6\">le<\/span><span class=\"s6\"> attivit\u00e0 di natura promozionale e pubblicitaria (invio di comunicazioni di marketing<\/span><span class=\"s6\">, profilazione<\/span><span class=\"s6\"> e ricerche di mercato)<\/span><span class=\"s6\">. Per le attivit\u00e0 di trattamento non esplicitate nella presente informativa si prega di fare riferimento all\u2019apposita informativa <\/span><span class=\"s6\">generale per gli utenti del <\/span><span class=\"s6\">Sito<\/span><span class=\"s6\">.<\/span><\/p><p class=\"s7\"><span class=\"s6\">I trattamenti dei dati sono svolti:<\/span><\/p><div class=\"s10\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">congiuntamente da <\/span><span class=\"s6\">Euthalia<\/span><span class=\"s6\"> S.r.l. e AFA <\/span><span class=\"s6\">S.r.l.s<\/span><span class=\"s6\"> in qualit\u00e0 di Contitolari del trattamento ex art. 26 GDPR, per le finalit\u00e0 indicate ai punti 3.<\/span><span class=\"s6\">2<\/span><span class=\"s6\"> e 3.<\/span><span class=\"s6\">4<\/span><span class=\"s6\">;<\/span><\/div><div class=\"s10\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">individualmente <\/span><span class=\"s6\">da AFA <\/span><span class=\"s6\">S.r.l.s<\/span><span class=\"s6\">. in qualit\u00e0 di Titolare autonomo del trattamento, per le <\/span><span class=\"s6\">finalit\u00e0 indicate ai punti 3.1 e 3.3;<\/span><\/div><div class=\"s10\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">individualmente da <\/span><span class=\"s6\">Euthalia<\/span><span class=\"s6\"> S.r.l. in qualit\u00e0 di Titolare autonomo del trattamento, per le finalit\u00e0 indicate al punto 3.<\/span><span class=\"s6\">5<\/span><span class=\"s6\">.<\/span><\/div><div class=\"s14\"><span class=\"s12\">1. <\/span><span class=\"s13\">Contitolari<\/span><span class=\"s13\"> del trattamento<\/span><span class=\"s13\">*<\/span><\/div><table style=\"height: 578px;\" width=\"600\"><tbody><tr><td class=\"s15\"><div><table style=\"height: 405px;\" width=\"336\"><tbody><tr><td class=\"s16\"><div><p><span class=\"s13\">Contitolare 1<\/span><\/p><p class=\"s17\"><span class=\"s13\">Euthalia<\/span><span class=\"s13\"> S.r.l.<\/span><\/p><p class=\"s17\"><span class=\"s6\">Sede Legale: <\/span><\/p><p class=\"s17\"><span class=\"s6\">Via Ignazio Ciampi n. 18,<\/span><span class=\"s6\"><br \/><\/span><span class=\"s6\">00162 \u2013 Roma (RM)<\/span><span class=\"s6\"><br \/><\/span><span class=\"s6\">Contatto e-mail:\u00a0<\/span><a href=\"mailto:privacy@euthalia.it\"><span class=\"s18\">privacy@euthalia.it<\/span><\/a><\/p><p><strong>Responsabile per la Protezione dei Dati (RPD\/DPO)<\/strong><\/p><p><strong>Avv. Vera Cantoni<\/strong><br \/>Domicilio per l\u2019incarico: Via F. Turati n. 26, 20121 \u2013 Milano (MI)<br \/>Contatto e-mail:\u00a0<a href=\"mailto:dpo@euthalia.it\">dpo@euthalia.it<\/a><\/p><\/div><\/td><td class=\"s16\"><div><p class=\"s17\">\u00a0<\/p><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/td><\/tr><tr><td class=\"s15\"><div><table><tbody><tr><td class=\"s16\"><div><p><span class=\"s13\">Contitolare 2<\/span><\/p><p><span class=\"s13\">AFA<\/span> <span class=\"s13\">S.r.l.<\/span><span class=\"s13\">s<\/span><span class=\"s13\">.<\/span><\/p><p><span class=\"s6\">Sede Legale:<\/span><\/p><p><span class=\"s6\">Via Matteotti, n. 6<\/span><span class=\"s6\">,<\/span><\/p><p><span class=\"s6\">25010 &#8211; Montirone (BS)<\/span><\/p><p><span class=\"s6\">Contatto e-mail:\u00a0<\/span><a href=\"mailto:coccolatevi@afaitalia.it\"><span class=\"s18\">coccolatevi@afaitalia.it<\/span><\/a><\/p><\/div><\/td><td class=\"s16\"><div><p class=\"s17\">\u00a0<\/p><\/div><\/td><\/tr><\/tbody><\/table><\/div><\/td><\/tr><\/tbody><\/table><p class=\"s20\"><span class=\"s19\">* <\/span><span class=\"s19\">Il contenuto essenziale dell\u2019accordo di contitolarit\u00e0 \u00e8 a disposizione degli interessati dietro esplicita richiesta.<\/span><\/p><div class=\"s21\"><span class=\"s12\">2. <\/span><span class=\"s13\">Le categorie di dati che v<\/span><span class=\"s13\">engono sottoposti a trattamento<\/span><\/div><p class=\"s23\"><span class=\"s22\">Le categorie di \u201cdati personali\u201d (ex. Art. 4.1 del GDPR) trattati <\/span><span class=\"s22\">dai Contitolari<\/span><span class=\"s22\"> possono essere, a mero titolo esemplificativo ma certo non esaustivo:<\/span><\/p><div class=\"s25\"><span class=\"s24\">\u00ad <\/span><span class=\"s6\">Dati anagrafici e identificativi (<\/span><span class=\"s6\">informazioni necessarie per completare l\u2019acquisto, tra cui il <\/span><span class=\"s6\">nome<\/span><span class=\"s6\"> e<\/span> <span class=\"s6\">il <\/span><span class=\"s6\">cognome<\/span><span class=\"s6\">, la data e il luogo di nascita<\/span><span class=\"s6\">, ecc.);<\/span><\/div><div class=\"s25\"><span class=\"s24\">\u00ad <\/span><span class=\"s6\">Dati di contatto <\/span><span class=\"s6\">(<\/span><span class=\"s6\">informazioni necessarie per completare l\u2019acquisto<\/span><span class=\"s6\">, tra cui l\u2019<\/span><span class=\"s6\">indirizzo per <\/span><span class=\"s6\">la fatturazione e per la spedizione<\/span><span class=\"s6\">, indirizzo e-mail, numero di telefono<\/span><span class=\"s6\">)<\/span><span class=\"s6\">;<\/span><\/div><div class=\"s25\"><span class=\"s24\">\u00ad <\/span><span class=\"s6\">Dati di navigazione (quali, a titolo esemplificativo, indirizzo IP, ecc.);<\/span><\/div><div class=\"s25\"><span class=\"s24\">\u00ad <\/span><span class=\"s6\">Dati relativi <\/span><span class=\"s6\">ai metodi di pagamento<\/span><span class=\"s6\">;<\/span><\/div><div class=\"s25\"><span class=\"s24\">\u00ad <\/span><span class=\"s6\">Dati relativi ai servizi erogati e ai prodotti forniti (quali, a titolo esemplificativo, <\/span><span class=\"s6\">informazioni relative ai servizi di customer care, <\/span><span class=\"s6\">informazioni relative ai prodotti acquistati tramite i nostri canali di vendita e preferenze d\u2019acquisto, rilevabili anche dalle risposte ai nostri questionari di soddisfazione).<\/span><\/div><div class=\"s27\"><span class=\"s12\">3. <\/span><span class=\"s13\">Liceit\u00e0 e f<\/span><span class=\"s13\">inalit\u00e0 <\/span><span class=\"s13\">del trattamento<\/span><\/div><p class=\"s28\"><span class=\"s22\">Il trattamento dei dati personali avviene in conformit\u00e0 alle disposizioni del Regolamento generale sulla protezione dei dati (GDPR) e di ogni altra normativa sulla protezione dei dati applicabile. Di seguito vengono forniti i dettagli:<\/span><\/p><div class=\"s33\"><span class=\"s30\">3.1 <\/span><span class=\"s13\">Finalit\u00e0 volte <\/span><span class=\"s31\">all&#8217;adempimento di un obbligo legale <\/span><span class=\"s13\">(ex art. 6, paragrafo 1 (c) del GDPR)<\/span> <span class=\"s32\">perseguite individualmente da <\/span><span class=\"s32\">AFA<\/span> <span class=\"s32\">S.r.l.<\/span><span class=\"s32\">s<\/span><span class=\"s32\">.<\/span><span class=\"s32\"> in qualit\u00e0 di autonom<\/span><span class=\"s32\">o<\/span><span class=\"s32\"> Titolar<\/span><span class=\"s32\">e<\/span><span class=\"s32\"> del trattamento<\/span><\/div><div class=\"s25\"><span class=\"s34\">a. <\/span><span class=\"s22\">Adempimento di obblighi previsti da Leggi, Regolamenti e dalla Normativa Comunitaria, ovvero da disposizioni impartite da Autorit\u00e0 o da Organi di Vigilanza e Controllo in relazione o comunque connessi al contratto in essere e\/o futuro <\/span><span class=\"s22\">(quali, a titolo esemplificativo, adempimento della normativa fiscale, processi contabili e finanziari).<\/span><\/div><p class=\"s35\"><span class=\"s36\">Il periodo di <\/span><span class=\"s37\">conservazione<\/span><span class=\"s36\"> dei dati personali, relativamente alle finalit\u00e0 di cui alla presente sezione \u00e8:<\/span><\/p><p class=\"s35\"><span class=\"s6\">Per la <\/span><span class=\"s38\">finalit\u00e0: a<\/span><span class=\"s6\">, <\/span><span class=\"s39\">10 anni dal termine del rapporto contrattuale<\/span><span class=\"s39\"> \u2013 <\/span><span class=\"s39\">commerciale,<\/span> <span class=\"s36\">ossia <\/span><span class=\"s36\">dall\u2019effettuazione di ciascun<\/span><span class=\"s36\">acquisto<\/span><span class=\"s36\">. <\/span><\/p><p class=\"s35\"><span class=\"s36\">Questi tempi possono allungarsi in caso di contenzioso, di accertamenti delle autorit\u00e0 pubbliche o giudiziarie, nonch\u00e9 di eventuali disposizioni speciali di legge.<\/span><\/p><div class=\"s33\"><span class=\"s30\">3.2 <\/span><span class=\"s13\">Finalit\u00e0 volte all\u2019esecuzione di un contratto o di misure precontrattuali (ex art. 6, paragrafo 1 (b) del GDPR)<\/span><span class=\"s32\">perseguite <\/span><span class=\"s32\">congiuntamente<\/span><span class=\"s32\"> da <\/span><span class=\"s32\">Euthalia<\/span><span class=\"s32\"> S.r.l. e <\/span><span class=\"s32\">AFA<\/span> <span class=\"s32\">S.r.l.<\/span><span class=\"s32\">s<\/span><span class=\"s32\">.<\/span><span class=\"s32\"> in qualit\u00e0 di <\/span><span class=\"s32\">Contitolari<\/span><span class=\"s32\"> del trattamento<\/span><\/div><div class=\"s41\"><span class=\"s40\">a. <\/span><span class=\"s36\">A<\/span><span class=\"s36\">dempimento degli obblighi <\/span><span class=\"s36\">contrattuali connessi ai contratti d\u2019acquisto dei prodotti e servizi offerti<\/span> <span class=\"s36\">sul Sito <\/span><span class=\"s36\">(<\/span><span class=\"s36\">a titolo esemplificativo, <\/span><span class=\"s6\">esecuzione<\/span><span class=\"s6\"> e gestione degli ordini di acquisto <\/span><span class=\"s6\">d<\/span><span class=\"s6\">e<\/span><span class=\"s6\">i prodotti e <\/span><span class=\"s6\">dei <\/span><span class=\"s6\">servizi<\/span> <span class=\"s6\">presenti nel catalogo<\/span> <span class=\"s6\">del e-commerce<\/span><span class=\"s36\">,<\/span> <span class=\"s36\">spedizione<\/span><span class=\"s36\"> degli<\/span><span class=\"s36\"> ordini<\/span><span class=\"s36\"> per uno o pi\u00f9 <\/span><span class=\"s36\">prodotti<\/span><span class=\"s36\">);<\/span><\/div><div class=\"s41\"><span class=\"s40\">b. <\/span><span class=\"s36\">Gestione delle richieste da parte del servizio clienti, il quale utilizza i dati personali forniti per soddisfare le richieste d\u2019informazioni e le richieste d\u2019assistenza (qualora il richiedente non sia un cliente o utente, relativamente ai nostri prodotti e servizi, la base del trattamento non \u00e8 l\u2019esecuzione del contratto, ma il consenso ai sensi\u00a0<\/span><span class=\"s36\">dell\u2019<\/span><span class=\"s12\">art. 6 paragrafo 1 (a) del GDPR<\/span><span class=\"s36\">);<\/span><\/div><div class=\"s41\"><span class=\"s40\">c. <\/span><span class=\"s36\">T<\/span><span class=\"s36\">utela dei diritti contrattuali o comunque derivanti dai rapporti intercorrenti tra le <\/span><span class=\"s36\">P<\/span><span class=\"s36\">arti<\/span><span class=\"s36\">. <\/span><span class=\"s6\">Si precisa che, qualora la tutela dei diritti non sia direttamente connessa con l\u2019adempimento del contratto stipulato, i connessi trattamenti hanno <\/span><span class=\"s13\">come base giuridica<\/span> <span class=\"s13\">il legittimo interesse,<\/span> <span class=\"s13\">(ex art. 6 paragrafo 1 (f) del GDPR)<\/span><span class=\"s13\">, di tipo cogente e derivante dal rapporto contrattuale instaurato tra le <\/span><span class=\"s13\">P<\/span><span class=\"s13\">arti.<\/span><\/div><p class=\"s35\"><span class=\"s36\">Il periodo di <\/span><span class=\"s37\">conservazione<\/span><span class=\"s36\"> dei dati personali, relativamente alle finalit\u00e0 di cui alla presente sezione \u00e8:<\/span><\/p><p class=\"s35\"><span class=\"s36\">Per le <\/span><span class=\"s37\">finalit\u00e0: a, <\/span><span class=\"s37\">c<\/span><span class=\"s36\">,<\/span><span class=\"s36\"> 10<\/span><span class=\"s36\"> anni dal termine del rap<\/span><span class=\"s36\">porto contrattuale \u2013 commerciale, ossia <\/span><span class=\"s36\">dall\u2019effettuazione di ciascun acquisto<\/span><span class=\"s36\">.<\/span><\/p><p class=\"s35\"><span class=\"s36\">Per<\/span><span class=\"s36\"> la <\/span><span class=\"s37\">finalit\u00e0: <\/span><span class=\"s37\">b<\/span><span class=\"s36\">, fino all\u2019espletamento della richiesta, salvo che i riscontri forniti e le informazioni scambiate, siano necessari per dimostrare l\u2019assolvimento degli obblighi contrattuali o derivanti dai rapporti giuridici instaurati (in tal caso il periodo di conservazione sar\u00e0 pari a quello sopra indicato per le lettere a, <\/span><span class=\"s36\">c<\/span><span class=\"s36\">).<\/span><\/p><p class=\"s35\"><span class=\"s36\">Questi tempi possono allungarsi in caso di contenzioso.<\/span><\/p><div class=\"s33\"><span class=\"s30\">3.3 <\/span><span class=\"s13\">Finalit\u00e0 volte all\u2019esecuzione di un contratto o di misure precontrattuali (ex art. 6, paragrafo 1 (b) del GDPR)<\/span><span class=\"s32\">perseguite <\/span><span class=\"s32\">individualmente<\/span><span class=\"s32\"> da <\/span><span class=\"s32\">AFA<\/span> <span class=\"s32\">S.r.l.<\/span><span class=\"s32\">s<\/span><span class=\"s32\">.<\/span><span class=\"s32\"> in qualit\u00e0 di autonom<\/span><span class=\"s32\">o<\/span><span class=\"s32\"> Titolar<\/span><span class=\"s32\">e<\/span><span class=\"s32\"> del trattamento<\/span><\/div><div class=\"s42\">a. <span class=\"s36\">Gestione dei processi amministrativi, contabili, fiscali e finanziari connessi all&#8217;erogazione del prodotto<\/span><span class=\"s36\"> o del servizio<\/span><span class=\"s36\">fornito<\/span><span class=\"s36\"> tramite l\u2019e-commerce<\/span><span class=\"s36\"> (a titolo esemplificativo, emissione dei documenti fiscali<\/span><span class=\"s36\">,<\/span><span class=\"s36\"> ecc.)<\/span><span class=\"s36\">.<\/span><\/div><p class=\"s35\"><span class=\"s36\">Per l<\/span><span class=\"s36\">a<\/span> <span class=\"s37\">finalit\u00e0: a<\/span><span class=\"s36\">,<\/span><span class=\"s36\"> 10<\/span><span class=\"s36\"> anni dal termine del rapporto contrattuale<\/span><span class=\"s36\"> \u2013 commerciale, ossia <\/span><span class=\"s36\">dall\u2019effettuazione di ciascun <\/span><span class=\"s36\">acquisto.<\/span><\/p><div class=\"s33\"><span class=\"s30\">3.4 <\/span><span class=\"s13\">Finalit\u00e0 <\/span><a name=\"_Hlk497593715\"><\/a><span class=\"s13\">per il perseguimento di un legittimo interesse <\/span><span class=\"s13\">(ex art. 6 paragrafo 1 (f) del GDPR)<\/span> <span class=\"s43\">congiuntamente da <\/span><span class=\"s32\">Euthalia<\/span><span class=\"s32\"> S.r.l. e <\/span><span class=\"s32\">AFA<\/span> <span class=\"s32\">S.r.l.<\/span><span class=\"s32\">s<\/span><span class=\"s32\">.<\/span><span class=\"s43\"> in qualit\u00e0 di Contitolari del trattamento<\/span><\/div><div class=\"s45\">a. <span class=\"s44\">Attivit\u00e0 di verifica e controllo antifrode in ambito e-commerce<\/span><span class=\"s44\">, <\/span><span class=\"s39\">in relazione agli ordini dei clienti e ai pagamenti online effettuati dagli stessi;<\/span><\/div><div class=\"s45\">b. <span class=\"s44\">Tutela dei diritti derivanti dai rapporti intercorrenti tra le <\/span><span class=\"s44\">P<\/span><span class=\"s44\">arti di natura extracontrattuale o comunque non direttamente connessi con l\u2019adempimento del contratto stipulato<\/span><span class=\"s44\">;<\/span><\/div><div class=\"s45\">c. <span class=\"s44\">Svolgimento di indagini statistiche in forma aggregata, sotto forma di report di analisi, in relazione ai centri di ricavo<\/span><span class=\"s44\">;<\/span><\/div><div class=\"s45\">d. <span class=\"s44\">Svolgimento di attivit\u00e0 pubblicitarie o promozionali, nell\u2019accezione pi\u00f9 ampia del termine (ad esempio invio di newsletter e materiale informativo, richiesta di brochure, organizzazione di eventi, ecc.) tramite mail, a fini di vendita di prodotti o servizi analoghi agli acquisti effettuati dall\u2019interessato.<\/span><\/div><p class=\"s35\"><span class=\"s36\">Il periodo di <\/span><span class=\"s37\">conservazione<\/span><span class=\"s36\"> dei dati personali, relativamente alle finalit\u00e0 di cui alla presente sezione \u00e8:<\/span><\/p><p class=\"s35\"><span class=\"s36\">Per l<\/span><span class=\"s36\">e<\/span> <span class=\"s37\">finalit\u00e0<\/span><span class=\"s37\">:<\/span> <span class=\"s37\">a<\/span><span class=\"s36\">,<\/span> <span class=\"s36\">10 anni dal termine del rapporto contrattuale \u2013 commerciale, ossia dall\u2019effettuazione di ciascun acquisto.<\/span><\/p><p class=\"s35\"><span class=\"s36\">Per la <\/span><span class=\"s37\">finalit\u00e0<\/span><span class=\"s37\">:<\/span> <span class=\"s37\">b<\/span><span class=\"s36\">,<\/span><span class=\"s36\"> 5 anni dal verificarsi dell\u2019evento oggetto di tutela giuridica.<\/span><\/p><p class=\"s35\"><span class=\"s36\">Per la <\/span><span class=\"s37\">finalit\u00e0<\/span><span class=\"s37\">:<\/span> <span class=\"s37\">c<\/span><span class=\"s36\">, <\/span><span class=\"s36\">i dati vengono aggregati al momento della raccolta<\/span><span class=\"s36\">.<\/span><\/p><p class=\"s35\"><span class=\"s36\">Per la <\/span><span class=\"s37\">finalit\u00e0<\/span><span class=\"s37\">:<\/span> <span class=\"s37\">d<\/span><span class=\"s36\">, per la durata del rapporto contrattuale &#8211; commerciale instaurato e, comunque, fino a 24 mesi dall\u2019ultimo acquisto effettuato, salvo opposizione dell\u2019interessato. <\/span><span class=\"s12\">A tal proposito si specifica che l\u2019eventuale negazione o revoca del consenso per altre finalit\u00e0 di marketing, diverse dalla suddetta finalit\u00e0 a, non equivale ad opposizione alla stessa e non comporter\u00e0 la cessazione di tale finalit\u00e0 e delle attivit\u00e0 connesse<\/span><span class=\"s36\">.<\/span><\/p><p class=\"s48\"><span class=\"s22\">Questi tempi possono allungarsi in caso di contenzioso<\/span><span class=\"s22\"> o disposizione di legge<\/span><span class=\"s22\">.<\/span><\/p><div class=\"s33\"><span class=\"s30\">3.5 <\/span><span class=\"s13\">Finalit\u00e0 <\/span><a name=\"_Hlk1639961\"><\/a><span class=\"s13\">coperte dal consenso dell&#8217;interessato<\/span><span class=\"s13\"> (<\/span><span class=\"s13\">ex a<\/span><span class=\"s13\">rt. 6, paragrafo 1 (a) del GDPR)<\/span> <span class=\"s32\">perseguite <\/span><span class=\"s32\">individualmente<\/span><span class=\"s32\"> da <\/span><span class=\"s32\">Euthalia<\/span><span class=\"s32\"> S.r.l.<\/span><span class=\"s32\"> in qualit\u00e0 di autonom<\/span><span class=\"s32\">o<\/span><span class=\"s32\"> Titolar<\/span><span class=\"s32\">e<\/span><span class=\"s32\"> del trattamento<\/span><\/div><p class=\"s49\"><span class=\"s36\">Le finalit\u00e0 <\/span><span class=\"s44\">che richiedono il consenso sono:<\/span><\/p><div class=\"s50\"><span class=\"s34\">a) <\/span><a name=\"_Hlk17830102\"><\/a><span class=\"s22\">Svolgimento di attivit\u00e0 pubblicitarie o promozionali, nell\u2019accezione pi\u00f9 ampia del termine (ad esempio<\/span><span class=\"s22\">,<\/span><span class=\"s22\"> invio di newsletter e materiale informativ<\/span><span class=\"s22\">o in merito alle promozioni, agli sconti, ai concorsi, alle operazioni a premi e alle ulteriori iniziative commerciali condotte da <\/span><span class=\"s22\">Euthalia<\/span><span class=\"s22\">, nonch\u00e9<\/span><span class=\"s22\"> richiesta di brochure, organizzazione di eventi, ecc.) e altre attivit\u00e0 di marketing, tramite modalit\u00e0 automatizzate di contatto (ad esempio:<\/span><span class=\"s22\"> e-<\/span><span class=\"s22\">mail, sms e sistemi di messaggistica vari, anche istantanei e su internet, anche verso telefoni mobili);<\/span><\/div><div class=\"s50\"><span class=\"s34\">b) <\/span><a name=\"_Hlk17899790\"><\/a><span class=\"s22\">Attivit\u00e0 di profilazione per analizzare o prevedere aspetti riguardanti le<\/span> <span class=\"s22\">preferenze personali, <\/span><span class=\"s22\">gli <\/span><span class=\"s22\">interessi, i comportamenti e le abitudini commerciali<\/span><span class=\"s22\"> dell\u2019utente<\/span><span class=\"s22\">. <\/span><span class=\"s22\">Le informazioni raccolte, a titolo esemplificativo, attraverso gli acquisti effettuati e le pagine da lei visitate, vengono utilizzate per comprendere le sue abitudini di consumo e per poterle inviare comunicazioni pubblicitarie o promozionali personalizzate in base ai suoi interessi. <\/span><span class=\"s22\">Si precisa che la profilazione viene svolta con l\u2019ausilio di processi decisionali automatizzati, i quali tuttavia non producono effetti giuridici <\/span><span class=\"s22\">riguardanti l\u2019interessato<\/span><span class=\"s22\"> n\u00e9 incidono in modo analogo significativamente sulla <\/span><span class=\"s22\">sua<\/span><span class=\"s22\"> persona, come dettagliato dall\u2019articolo 22 del GDPR, in quanto effettuata con esclusivo riferimento alle attivit\u00e0 pubblicitarie o promozionali (marketing)<\/span><span class=\"s22\">;<\/span><\/div><div class=\"s50\"><span class=\"s34\">c) <\/span><span class=\"s22\">Svolgimento di attivit\u00e0 di ricerche e indagini di mercato (a titolo esemplificativo, esecuzione di studi di mercato e analisi statistiche in merito al grado di soddisfazione del cliente), tramite modalit\u00e0 automatizzate di contatto (ad esempio: <\/span><span class=\"s22\">e-<\/span><span class=\"s22\">mail, sms e sistemi di messaggistica vari, anche istantanei e su internet, anche verso telefoni mobili)<\/span><span class=\"s22\">.<\/span><\/div><p class=\"s29\"><span class=\"s22\">Il periodo di <\/span><span class=\"s52\">conservazione<\/span> <span class=\"s22\">dei dati personali, relativamente alle finalit\u00e0 di cui alla presente sezione \u00e8:<\/span><\/p><p class=\"s53\"><span class=\"s6\">Per la <\/span><span class=\"s38\">finalit\u00e0: a<\/span><span class=\"s6\">, <\/span><span class=\"s6\">24 mesi, dal rilascio<\/span><span class=\"s6\"> del consenso, salvo revoca.<\/span><\/p><p class=\"s53\"><span class=\"s6\">Per le <\/span><span class=\"s38\">finalit\u00e0: <\/span><span class=\"s54\">b, c<\/span><span class=\"s39\">: <\/span><span class=\"s6\">12 mesi, dal rilascio del consenso, salvo revoca.<\/span><\/p><div class=\"s55\"><span class=\"s12\">4. <\/span><a name=\"_Hlk485575911\"><\/a><span class=\"s13\">Destinatari o categorie di destinatari dei dati personali<\/span><span class=\"s13\"> (ex art. 13 paragrafo <\/span><span class=\"s13\">1 (e) <\/span><span class=\"s13\">del GDPR<\/span><span class=\"s13\">)<\/span> <span class=\"s13\">*<\/span><\/div><p class=\"s56\"><span class=\"s6\">Nell&#8217;ambito delle suindicate finalit\u00e0, i<\/span><span class=\"s6\"> Contitolari<\/span><span class=\"s6\"> del trattamento <\/span><span class=\"s6\">potr<\/span><span class=\"s6\">anno<\/span><span class=\"s6\"> comunicare i<\/span><span class=\"s6\"> s<\/span><span class=\"s6\">uoi dati<\/span><span class=\"s6\"> a<\/span><span class=\"s6\">:<\/span><\/p><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">Uffici ed alle funzioni interne <\/span><span class=\"s6\">di ciascun<\/span><span class=\"s6\"> Contitolar<\/span><span class=\"s6\">e<\/span><span class=\"s6\">;<\/span><\/div><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">Consulenti per la gestione contabilit\u00e0 e commercialisti;<\/span><\/div><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">Societ\u00e0 e operatori professionali che forniscono servizi informatici, tra cui elaborazione elettronica dei dati, di gestione software e dei cloud, gestione di siti internet e di consulenza informatica;<\/span><\/div><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">P<\/span><span class=\"s6\">rofessionisti abilitati al fine dello studio e risoluzione di eventuali problemi legali e contrattuali, inclusi avvocati e fiscalisti;<\/span><\/div><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">Societ\u00e0 e agenzie di pubblicit\u00e0 e di comunicazione;<\/span><\/div><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">Corrieri postali e societ\u00e0 che svolgono attivit\u00e0 di imbustamento e spedizione dei prodotti;<\/span><\/div><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">Agenzia delle Entrate e altre Pubbliche Amministrazioni e autorit\u00e0 pubbliche<\/span><span class=\"s6\">;<\/span><\/div><div class=\"s57\"><span class=\"s9\">\u2022 <\/span><span class=\"s6\">Societ\u00e0 che forniscono servizi di pagamento e gestione delle transazioni online nell\u2019ambito dell\u2019e-commerce<\/span><span class=\"s6\">.<\/span><\/div><p class=\"s59\"><span class=\"s6\">* <\/span><span class=\"s19\">L\u2019elenco completo ed aggiornato dei<\/span><span class=\"s19\"> Destinatari (ex art. 4.9 del GDPR) <\/span><span class=\"s19\">\u00e8<\/span><span class=\"s19\"> disponibil<\/span><span class=\"s19\">e<\/span><span class=\"s19\"> presso <\/span><span class=\"s19\">i Contitolari<\/span><span class=\"s19\"> del trattamento dei dati personali ai recapiti sopra indicati<\/span><span class=\"s19\">.<\/span><\/p><div class=\"s33\"><span class=\"s12\">5. <\/span><a name=\"_Hlk1584347\"><\/a><span class=\"s13\">Destinatari o categorie di destinatari dei dati personali (ex art. 13 paragrafo 1 (f) del GDPR) <\/span><span class=\"s13\">* <\/span><span class=\"s13\">e trasferimento dei dati in Paesi extra UE<\/span><\/div><p class=\"s60\"><span class=\"s6\">I Contitolari le comunicano <\/span><span class=\"s6\">che <\/span><span class=\"s6\">nell\u2019ambito del<\/span><span class=\"s6\">le finalit\u00e0 sopra indicate, <\/span><span class=\"s6\">potranno <\/span><span class=\"s6\">trasferire i <\/span><span class=\"s6\">suoi<\/span><span class=\"s6\"> dati in paesi non compresi nella UE e nella SEE<\/span><span class=\"s6\">,<\/span> <span class=\"s6\">anche tramite soggetti terzi incaricati dallo stesso, che agiscono in qualit\u00e0 di Responsabili del trattamento, nonch\u00e9 tramite i Sub-fornitori di quest\u2019ultimi<\/span><span class=\"s6\">. In tali casi,<\/span><span class=\"s6\"> il trasferimento avverr\u00e0 in conformit\u00e0 con quanto stabilito dagli artt. 44 e ss. del GDPR e dalle disposizioni di legge applicabili stipulando, se necessario, accordi che garantiscano un livello di protezione adeguato<\/span><span class=\"s6\"> o fornendo altre garanzie di adeguatezza tra quelle espressamente previste dagli articoli sopra richiamati<\/span><span class=\"s6\">. Pertanto, tutte le volte in cui i <\/span><span class=\"s6\">suoi<\/span><span class=\"s6\"> dati personali dovessero essere oggetto di trasferimento al di fuori dello SEE e, in particolare, verso Stati che non beneficiano di una decisione di adeguatezza della Commissione Europea **, il Titolare adotter\u00e0 una delle <\/span><span class=\"s6\">condizioni di legittimit\u00e0<\/span><span class=\"s6\"> a tal fine previste dalla Normativa applicabile.<\/span><\/p><p class=\"s60\"><span class=\"s6\">In particolare, <\/span><span class=\"s6\">per le finalit\u00e0 3.2,<\/span> <span class=\"s6\">lett. a) e 3.4, lett. a), <\/span><span class=\"s6\">i suoi dati <\/span><span class=\"s6\">verranno<\/span><span class=\"s6\"> trasferiti <\/span><span class=\"s6\">negli Stati Uniti d\u2019America <\/span><span class=\"s6\">alla societ\u00e0 <\/span><span class=\"s6\">Stripe <\/span><span class=\"s6\">Payments Europe Ltd e all\u2019azienda <\/span><span class=\"s6\">controllante<\/span><span class=\"s6\"> Stripe Inc., <\/span><span class=\"s6\">che aderisce al Data Privacy Framework, nonch\u00e9 verso ulteriori paesi <\/span><span class=\"s6\">non compresi nella UE e nella SEE<\/span><span class=\"s6\"> presso cui operano tali aziende e i sub-fornitori delle stesse.<\/span><\/p><p class=\"s60\"><span class=\"s6\">Per maggiori dettagli, l\u2019interessato pu\u00f2 fare richiesta <\/span><span class=\"s6\">ai Contitolari<\/span><span class=\"s6\"> tramite i contatti di cui al punto 1 della presente informativa.<\/span><\/p><p class=\"s61\"><span class=\"s6\">* <\/span><span class=\"s19\">L\u2019elenco completo ed aggiornato dei Destinatari (ex art. 4.9 del GDPR) \u00e8 disponibile presso i Contitolari del trattamento dei dati personali ai recapiti sopra indicati.<\/span><\/p><p class=\"s61\"><span class=\"s19\">** <\/span><span class=\"s19\">La lista aggiornata dei paesi adeguati extra-SEE ritenuti adeguati dalla Commissione Europea potr\u00e0 ottenersi sul sito web: <\/span><a href=\"https:\/\/commission.europa.eu\/law\/law-topic\/data-protection\/international-dimension-data-protection\/adequacy-decisions_en\" target=\"_blank\" rel=\"noopener\"><span class=\"s62\">Adequacy<\/span> <span class=\"s62\">decisions<\/span><span class=\"s62\"> (europa.eu)<\/span><\/a><\/p><div class=\"s21\"><span class=\"s12\">6. <\/span><span class=\"s13\">Diritti del Soggetto Interessato (ex. <\/span><span class=\"s13\">a<\/span><span class=\"s13\">rt.<\/span><span class=\"s13\"> 13 <\/span><span class=\"s13\">paragrafo <\/span><span class=\"s13\">2 (b) <\/span><span class=\"s13\">del GDPR<\/span><span class=\"s13\">)<\/span><\/div><p class=\"s20\"><span class=\"s6\">L\u2019interessato pu\u00f2 far valere i seguenti diritti:<\/span><\/p><div class=\"s65\"><span class=\"s64\">\u2022 <\/span><span class=\"s22\">diritto di <\/span><span class=\"s22\">accesso dell\u2019interessato [art. 15 del Regolamento UE]<\/span> <span class=\"s22\">(la possibilit\u00e0 di essere informato sui trattamenti effettuati sui propri Dati Personali ed eventualmente riceverne copia);<\/span><\/div><div class=\"s65\"><span class=\"s64\">\u2022 <\/span><span class=\"s22\">diritto di rettifica dei propri Dati Personali [art. 16 del Regolamento UE] (l\u2019interessato ha diritto alla rettifica dei dati personali inesatti che lo riguardano);<\/span><\/div><div class=\"s65\"><span class=\"s64\">\u2022 <\/span><span class=\"s22\">diritto alla cancellazione dei propri Dati Personali senza ingiustificato ritardo (\u201cdiritto all\u2019oblio\u201d) [art. 17 del Regolamento UE] (l\u2019interessato ha, cos\u00ec come avr\u00e0, diritto alla cancellazione dei propri dati);<\/span><\/div><div class=\"s65\"><span class=\"s64\">\u2022 <\/span><span class=\"s22\">diritto di limitazione di trattamento dei propri Dati Personali nei casi previsti dall\u2019art. 18 del Regolamento UE, tra cui nel caso di trattamenti illeciti o contestazione dell\u2019esattezza dei Dati Personali da parte dell\u2019interessato [art. 18 del Regolamento UE];<\/span><\/div><div class=\"s65\"><span class=\"s64\">\u2022 <\/span><span class=\"s22\">diritto alla portabilit\u00e0 dei dati [art. 20 del Regolamento UE], l\u2019interessato potr\u00e0 richiedere in formato strutturato i propri Dati Personali al fine di trasmetterli ad altro titolare, nei casi previsti dal medesimo articolo;<\/span><\/div><div class=\"s65\"><span class=\"s64\">\u2022 <\/span><span class=\"s22\">diritto di opposizione al trattamento dei propri Dati Personali [art. 21 del Regolamento UE] (l\u2019interessato ha, cos\u00ec come avr\u00e0, diritto alla opposizione del trattamento dei propri dati personali);<\/span><\/div><div class=\"s65\"><span class=\"s64\">\u2022 <\/span><span class=\"s22\">diritto di non essere sottoposto a processi decisionali automatizzati,<\/span> <span class=\"s22\">[art. 22 del Regolamento UE] (l\u2019interessato ha, cos\u00ec come avr\u00e0, diritto a non essere sottoposto ad una decisione basata unicamente sul trattamento automatizzato).<\/span><\/div><p class=\"s63\"><span class=\"s22\">Ulteriori informazioni circa i diritti dell\u2019interessato potranno ottenersi richiedendo <\/span><span class=\"s22\">ad uno dei Contitolari <\/span><span class=\"s22\">estratto integrale degli articoli sopra richiamati.\u00a0<\/span><\/p><p class=\"s63\"><a name=\"_Hlk2190728\"><\/a><span class=\"s22\">I <\/span><span class=\"s22\">suddetti diritti possono essere esercitati secondo quanto stabilito dal Regolamento inviando, anche, una e-mail ai Contitolari, anche singolarmente, ai seguenti indirizzi:<\/span><\/p><div class=\"s69\"><span class=\"s67\">\u2022 <\/span><span class=\"s6\">Euthalia<\/span><span class=\"s6\"> S.r.l.: <\/span><a href=\"mailto:privacy@euthalia.it\"><span class=\"s18\">privacy@euthalia.it<\/span><\/a><span class=\"s68\">;<\/span><\/div><div class=\"s69\"><span class=\"s67\">\u2022 <\/span><span class=\"s6\">AFA <\/span><span class=\"s6\">S.r.l.s<\/span><span class=\"s6\">.<\/span><span class=\"s6\">: <\/span><span class=\"s70\">\u00a0<\/span><a href=\"mailto:coccolatevi@afaitalia.it\"><span class=\"s18\">coccolatevi@afaitalia.it<\/span><\/a><span class=\"s6\">.<\/span><\/div><p class=\"s63\"><span class=\"s22\">I<\/span><span class=\"s22\">n ossequio all\u2019art. 19 del Regolamento UE, <\/span><span class=\"s22\">i Contitolari<\/span> <span class=\"s22\">proced<\/span><span class=\"s22\">ono<\/span><span class=\"s22\"> a<\/span><span class=\"s22\">d<\/span><span class=\"s22\"> informare i destinatari cui sono stati comunicati i dati personali, le eventuali rettifiche, cancellazioni o limitazioni del trattamento richieste, ove ci\u00f2 sia possibile. <\/span><\/p><p class=\"s63\"><span class=\"s22\">Per consentire un pi\u00f9 celere riscontro delle Sue richieste formulate nell&#8217;esercizio dei su indicati diritti, le stesse potranno essere rivolte <\/span><span class=\"s22\">ai Contitolari, anche singolarmente<\/span><span class=\"s22\">,<\/span><span class=\"s22\"> indirizzando le medesime ai recapiti indicati al punto 1.<\/span><\/p><div class=\"s73\"><span class=\"s72\">7. <\/span><span class=\"s72\">Diritto di proporre reclamo (<\/span><span class=\"s72\">ex <\/span><span class=\"s72\">art. 13 <\/span><span class=\"s72\">paragrafo <\/span><span class=\"s72\">2 (d) del GDPR)<\/span><\/div><p class=\"s66\"><span class=\"s22\">L\u2019interessato, qualora ritenga che i propri diritti siano stati compromessi, ha diritto di proporre reclamo all\u2019Autorit\u00e0 Garante per la protezione dei dati personali, secondo le modalit\u00e0 indicate dalla stessa Autorit\u00e0 al seguente indirizzo <\/span><span class=\"s22\">I<\/span><span class=\"s22\">nternet <\/span><a href=\"http:\/\/www.garanteprivacy.it\/web\/guest\/home\/docweb\/-\/docweb-display\/docweb\/4535524\" target=\"_blank\" rel=\"noopener\"><span class=\"s74\">http:\/\/www.garanteprivacy.it\/web\/guest\/home\/docweb\/-\/docweb-display\/docweb\/4535524<\/span><\/a> <span class=\"s22\">oppure inviando comunicazione<\/span><span class=\"s22\"> scritta<\/span><span class=\"s22\"> all<\/span><span class=\"s22\">\u2019<\/span><span class=\"s22\"> Autorit\u00e0 Garante per la Protezione dei Dati Personali.<\/span><\/p><div class=\"s73\"><span class=\"s72\">8. <\/span><span class=\"s72\">Possibile conseguenza della mancata comunicazione dei dati <\/span><span class=\"s72\">e natura del conferimento dei dati <\/span><span class=\"s72\">(<\/span><span class=\"s72\">ex <\/span><span class=\"s72\">art. 13 paragrafo 2 (e) del GDPR)<\/span><\/div><div class=\"s75\"><span class=\"s34\">8.1 <\/span><a name=\"_Hlk17301715\"><\/a><span class=\"s72\">In caso di adempimento di obblighi di legge o contrattuali<\/span><\/div><p class=\"s76\"><span class=\"s22\">Si informa <\/span><span class=\"s22\">che<\/span><span class=\"s22\"> qualora le finalit\u00e0 di trattamento abbiano come base giuridica un obbligo legale o contrattuale (o anche precontrattuale), l\u2019interessato deve necessariamente fornire i dati richiesti.<\/span><\/p><p class=\"s76\"><span class=\"s22\">In caso contrario vi sar\u00e0 l\u2019impossibilit\u00e0 da parte <\/span><span class=\"s22\">dei Contitolari<\/span><span class=\"s22\"> di procedere al perseguimento delle specifiche finalit\u00e0 di trattamento.<\/span><\/p><div class=\"s75\"><span class=\"s34\">8.2 <\/span><span class=\"s72\">In caso di perseguimento di legittimo interesse<\/span><\/div><p class=\"s76\"><span class=\"s22\">Parimenti, relativamente alle finalit\u00e0 basate su un interesse legittimo e che non richiedono il consenso, l\u2019opposizione dell\u2019interessato comporta o comporter\u00e0 l\u2019impossibilit\u00e0 di procedere alla realizzazione delle rispettive finalit\u00e0 e degli eventuali servizi connessi, per cui rispettivamente l\u2019interessato si \u00e8 opposto, fatti salvi motivi legittimi cogenti prevalenti del Titolari o finalizzati alla tutela di diritti in sede giudiziaria.<\/span><\/p><p class=\"s29\"><a name=\"_Hlk17301678\"><\/a><span class=\"s72\">8.3<\/span>\u200b<span class=\"s72\">In caso di consenso dell&#8217;interessato<\/span><\/p><p class=\"s77\"><span class=\"s22\">Per altre finalit\u00e0, per le quali \u00e8 richiesto il consenso, l\u2019Interessato pu\u00f2 revocare il proprio consenso in qualsiasi momento e gli effetti decorreranno dal momento della revoca, fatti salvi i termini previsti dalla legge. In termini generali la revoca del consenso ha effetto solo per il futuro. Pertanto, il trattamento che \u00e8 stato effettuato prima della revoca del consenso non subir\u00e0 effetti e manterr\u00e0 la sua legittimit\u00e0.<\/span><\/p><p class=\"s77\"><span class=\"s22\">Il mancato o parziale consenso potrebbe non garantire l\u2019erogazione completa dei <\/span><span class=\"s22\">servizi, con riferimento <\/span><span class=\"s22\">alle singole<\/span><span class=\"s22\"> finalit\u00e0 per cui il consenso viene negato.<\/span><\/p><p class=\"s29\"><a name=\"_Hlk2190841\"><\/a><span class=\"s22\">Quando i dati non sono pi\u00f9 necessari<\/span><span class=\"s22\">, <\/span><span class=\"s22\">tenuto conto dei periodi di conservazione soprariportati,<\/span><span class=\"s22\"> questi vengono regolarmente cancellati<\/span><span class=\"s22\">. Q<\/span><span class=\"s22\">ualora la loro cancellazione risulti impossibile o possibile solo a fronte di uno sforzo sproporzionato a causa di una modalit\u00e0 di conservazione particolare il dato non potr\u00e0 essere trattato e dovr\u00e0 essere archiviato in aree non accessibili<\/span><span class=\"s22\">.<\/span><\/p><div class=\"s73\"><span class=\"s72\">9. <\/span><span class=\"s72\">Esistenza di <\/span><span class=\"s72\">processi decisionali<\/span><span class=\"s72\"> automatizzat<\/span><span class=\"s72\">i<\/span><span class=\"s72\"> non rilevant<\/span><span class=\"s72\">i<\/span><span class=\"s72\"> ai sensi dell\u2019articolo 22 del GDPR<\/span><\/div><p class=\"s78\"><span class=\"s36\">\u00c8 attualmente escluso l&#8217;uso di processi decisionali meramente automatizzati come dettagliato dall&#8217;articolo 22 del <\/span><span class=\"s36\">GDPR<\/span><span class=\"s36\">. <\/span><span class=\"s36\">Se in futuro si decidesse di istituire tali processi per casi singoli, l&#8217;interessato ne ricever\u00e0 notifica in separata sede qualora ci\u00f2 sia previsto dalla legge o aggiornamento della presente informativa.<\/span><\/p><p class=\"s78\"><span class=\"s36\">Si precisa che, in relazione alla finalit\u00e0 3.4, lett. a), sono adottati processi decisionali parzialmente automatizzati che non rientrano nell\u2019ambito di applicazione dell\u2019art. 22 GDPR: i controlli antifrode relativi all\u2019e-commerce prevedono l\u2019impiego di sistemi che segnalano eventuali attivit\u00e0 sospette degli utenti quando effettuano gli ordini di acquisto. Tali segnalazioni hanno funzione di supporto e non comportano blocchi automatici degli utenti, ma sono strumentali alle valutazioni e decisioni assunte autonomamente dai Contitolari del trattamento.<\/span><\/p><p class=\"s78\"><span class=\"s36\">Si precisa <\/span><span class=\"s36\">inoltre <\/span><span class=\"s36\">che in relazione alla finalit\u00e0 3.5 lett. <\/span><span class=\"s36\">b<\/span><span class=\"s36\">), previo il consenso <\/span><span class=\"s36\">dell\u2019interessato, vengono<\/span><span class=\"s36\"> adottati processi decisionali automatizzati che non rientrano nell\u2019ambito di applicazione dell\u2019articolo 22 del GDPR, <\/span><span class=\"s36\">in quanto effettuat<\/span><span class=\"s36\">i<\/span><span class=\"s36\"> con esclusivo riferimento alle attivit\u00e0 pubblicitarie o promozionali (marketing).<\/span><\/p><div class=\"s79\"><span class=\"s12\">10. <\/span><span class=\"s13\">Modalit\u00e0 del trattamento<\/span><\/div><p class=\"s80\"><span class=\"s6\">I dati personali verranno trattati in forma cartacea, informatizzata e telematica ed inseriti nelle pertinenti banche dati cui potranno accedere, e quindi venirne a conoscenza, gli addetti espressamente designati <\/span><span class=\"s6\">dai <\/span><span class=\"s6\">singoli Contitolari<\/span><span class=\"s6\"> quali Responsabili ed Autorizzati del trattamento dei dati personali, che potranno effettuare operazioni di consultazione, utilizzo, elaborazione, raffronto ed ogni altra opportuna operazione anche automatizzata nel rispetto delle disposizioni di legge necessarie a garantire, tra l&#8217;altro, la riservatezza e la sicurezza dei dati nonch\u00e9 l\u2019esattezza, l\u2019aggiornamento e la pertinenza dei dati rispetto alle finalit\u00e0 dichiarate.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informativa ecommerce INFORMATIVA PRIVACY AI SENSI DELL\u2019ART. 13 DEL REGOLAMENTO UE 2016\/679 per i Clienti dell\u2019e-commerce, in relazione all\u2019acquisto e alla consegna dei prodotti Euthalia nonch\u00e9 ai servizi di customer care, allo svolgimento dell\u2019attivit\u00e0 di marketing, di profilazione e alle ricerche di mercato Per noi la protezione dei dati \u00e8 un argomento molto serio per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4536","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/pages\/4536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/comments?post=4536"}],"version-history":[{"count":10,"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/pages\/4536\/revisions"}],"predecessor-version":[{"id":6508,"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/pages\/4536\/revisions\/6508"}],"wp:attachment":[{"href":"https:\/\/coccolatevi.it\/de\/wp-json\/wp\/v2\/media?parent=4536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}